{"id":2900,"date":"2022-12-28T01:29:47","date_gmt":"2022-12-28T00:29:47","guid":{"rendered":"https:\/\/new-web.palacenatali.com\/weddings-and-events\/"},"modified":"2025-09-12T14:14:54","modified_gmt":"2025-09-12T12:14:54","slug":"mariages-et-evenements","status":"publish","type":"page","link":"https:\/\/palacenatali.com\/fr\/mariages-et-evenements\/","title":{"rendered":"Mariages et \u00e9v\u00e9nements"},"content":{"rendered":"<p>Votre journ\u00e9e sp\u00e9ciale m\u00e9rite un lieu sp\u00e9cial. Que la beaut\u00e9 et la magie du Palace Natali rendent vos souvenirs encore plus merveilleux. Situ\u00e9 en plein c\u0153ur de la ville, mais suffisamment \u00e9loign\u00e9 de son agitation, le Palace Natali est, dans cette oasis de paix, le lieu parfait pour diff\u00e9rentes occasions : \u00e9v\u00e9nements priv\u00e9s et professionnels, petits mariages et c\u00e9l\u00e9brations.<\/p>\n<p><a class=\"btn btn-secondary btn-event-request\" style=\"margin-top: 40px;\" href=\"https:\/\/palacenatali.com\/fr\/demande-devenement\/\">Envoyez une demande<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Votre journ\u00e9e sp\u00e9ciale m\u00e9rite un lieu sp\u00e9cial. Que la beaut\u00e9 et la magie du Palace Natali rendent vos souvenirs encore plus merveilleux. Situ\u00e9 en plein c\u0153ur de la ville, mais suffisamment \u00e9loign\u00e9 de son agitation, le Palace Natali est, dans cette oasis de paix, le lieu parfait pour diff\u00e9rentes occasions : \u00e9v\u00e9nements priv\u00e9s et professionnels, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6386,"parent":0,"menu_order":80,"comment_status":"closed","ping_status":"closed","template":"template-events.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2900","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Votre journ\u00e9e sp\u00e9ciale m\u00e9rite un lieu sp\u00e9cial. Que la beaut\u00e9 et la magie du Palace Natali rendent vos souvenirs encore plus merveilleux. Situ\u00e9 en plein c\u0153ur de la ville, mais suffisamment \u00e9loign\u00e9 de son agitation, le Palace Natali est, dans cette oasis de paix, le lieu parfait pour diff\u00e9rentes occasions : \u00e9v\u00e9nements priv\u00e9s et professionnels,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/palacenatali.com\/fr\/mariages-et-evenements\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Palace Natali -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Mariages et \u00e9v\u00e9nements - Palace Natali\" \/>\n\t\t<meta property=\"og:description\" content=\"Votre journ\u00e9e sp\u00e9ciale m\u00e9rite un lieu sp\u00e9cial. Que la beaut\u00e9 et la magie du Palace Natali rendent vos souvenirs encore plus merveilleux. Situ\u00e9 en plein c\u0153ur de la ville, mais suffisamment \u00e9loign\u00e9 de son agitation, le Palace Natali est, dans cette oasis de paix, le lieu parfait pour diff\u00e9rentes occasions : \u00e9v\u00e9nements priv\u00e9s et professionnels,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/palacenatali.com\/fr\/mariages-et-evenements\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-12-28T00:29:47+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-09-12T12:14:54+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Mariages et \u00e9v\u00e9nements - Palace Natali\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Votre journ\u00e9e sp\u00e9ciale m\u00e9rite un lieu sp\u00e9cial. Que la beaut\u00e9 et la magie du Palace Natali rendent vos souvenirs encore plus merveilleux. Situ\u00e9 en plein c\u0153ur de la ville, mais suffisamment \u00e9loign\u00e9 de son agitation, le Palace Natali est, dans cette oasis de paix, le lieu parfait pour diff\u00e9rentes occasions : \u00e9v\u00e9nements priv\u00e9s et professionnels,\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/mariages-et-evenements\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/mariages-et-evenements\\\/#listItem\",\"name\":\"Mariages et \\u00e9v\\u00e9nements\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/mariages-et-evenements\\\/#listItem\",\"position\":2,\"name\":\"Mariages et \\u00e9v\\u00e9nements\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/#organization\",\"name\":\"Palace Natali\",\"url\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/\",\"telephone\":\"+38520325550\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/palacenatali.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo-natali.svg\",\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/mariages-et-evenements\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/mariages-et-evenements\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/mariages-et-evenements\\\/#webpage\",\"url\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/mariages-et-evenements\\\/\",\"name\":\"Mariages et \\u00e9v\\u00e9nements - Palace Natali\",\"description\":\"Votre journ\\u00e9e sp\\u00e9ciale m\\u00e9rite un lieu sp\\u00e9cial. Que la beaut\\u00e9 et la magie du Palace Natali rendent vos souvenirs encore plus merveilleux. Situ\\u00e9 en plein c\\u0153ur de la ville, mais suffisamment \\u00e9loign\\u00e9 de son agitation, le Palace Natali est, dans cette oasis de paix, le lieu parfait pour diff\\u00e9rentes occasions : \\u00e9v\\u00e9nements priv\\u00e9s et professionnels,\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/mariages-et-evenements\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/palacenatali.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/NC_1.jpg\",\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/mariages-et-evenements\\\/#mainImage\",\"width\":1920,\"height\":1281},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/mariages-et-evenements\\\/#mainImage\"},\"datePublished\":\"2022-12-28T01:29:47+01:00\",\"dateModified\":\"2025-09-12T14:14:54+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/\",\"name\":\"Palace Natali\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Mariages et \u00e9v\u00e9nements - Palace Natali","description":"Votre journ\u00e9e sp\u00e9ciale m\u00e9rite un lieu sp\u00e9cial. Que la beaut\u00e9 et la magie du Palace Natali rendent vos souvenirs encore plus merveilleux. Situ\u00e9 en plein c\u0153ur de la ville, mais suffisamment \u00e9loign\u00e9 de son agitation, le Palace Natali est, dans cette oasis de paix, le lieu parfait pour diff\u00e9rentes occasions : \u00e9v\u00e9nements priv\u00e9s et professionnels,","canonical_url":"https:\/\/palacenatali.com\/fr\/mariages-et-evenements\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/palacenatali.com\/fr\/mariages-et-evenements\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/palacenatali.com\/fr\/#listItem","position":1,"name":"Home","item":"https:\/\/palacenatali.com\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/palacenatali.com\/fr\/mariages-et-evenements\/#listItem","name":"Mariages et \u00e9v\u00e9nements"}},{"@type":"ListItem","@id":"https:\/\/palacenatali.com\/fr\/mariages-et-evenements\/#listItem","position":2,"name":"Mariages et \u00e9v\u00e9nements","previousItem":{"@type":"ListItem","@id":"https:\/\/palacenatali.com\/fr\/#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/palacenatali.com\/fr\/#organization","name":"Palace Natali","url":"https:\/\/palacenatali.com\/fr\/","telephone":"+38520325550","logo":{"@type":"ImageObject","url":"https:\/\/palacenatali.com\/wp-content\/uploads\/2024\/10\/logo-natali.svg","@id":"https:\/\/palacenatali.com\/fr\/mariages-et-evenements\/#organizationLogo"},"image":{"@id":"https:\/\/palacenatali.com\/fr\/mariages-et-evenements\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/palacenatali.com\/fr\/mariages-et-evenements\/#webpage","url":"https:\/\/palacenatali.com\/fr\/mariages-et-evenements\/","name":"Mariages et \u00e9v\u00e9nements - Palace Natali","description":"Votre journ\u00e9e sp\u00e9ciale m\u00e9rite un lieu sp\u00e9cial. Que la beaut\u00e9 et la magie du Palace Natali rendent vos souvenirs encore plus merveilleux. Situ\u00e9 en plein c\u0153ur de la ville, mais suffisamment \u00e9loign\u00e9 de son agitation, le Palace Natali est, dans cette oasis de paix, le lieu parfait pour diff\u00e9rentes occasions : \u00e9v\u00e9nements priv\u00e9s et professionnels,","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/palacenatali.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/palacenatali.com\/fr\/mariages-et-evenements\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/palacenatali.com\/wp-content\/uploads\/2025\/06\/NC_1.jpg","@id":"https:\/\/palacenatali.com\/fr\/mariages-et-evenements\/#mainImage","width":1920,"height":1281},"primaryImageOfPage":{"@id":"https:\/\/palacenatali.com\/fr\/mariages-et-evenements\/#mainImage"},"datePublished":"2022-12-28T01:29:47+01:00","dateModified":"2025-09-12T14:14:54+02:00"},{"@type":"WebSite","@id":"https:\/\/palacenatali.com\/fr\/#website","url":"https:\/\/palacenatali.com\/fr\/","name":"Palace Natali","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/palacenatali.com\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Palace Natali -","og:type":"article","og:title":"Mariages et \u00e9v\u00e9nements - Palace Natali","og:description":"Votre journ\u00e9e sp\u00e9ciale m\u00e9rite un lieu sp\u00e9cial. Que la beaut\u00e9 et la magie du Palace Natali rendent vos souvenirs encore plus merveilleux. Situ\u00e9 en plein c\u0153ur de la ville, mais suffisamment \u00e9loign\u00e9 de son agitation, le Palace Natali est, dans cette oasis de paix, le lieu parfait pour diff\u00e9rentes occasions : \u00e9v\u00e9nements priv\u00e9s et professionnels,","og:url":"https:\/\/palacenatali.com\/fr\/mariages-et-evenements\/","article:published_time":"2022-12-28T00:29:47+00:00","article:modified_time":"2025-09-12T12:14:54+00:00","twitter:card":"summary_large_image","twitter:title":"Mariages et \u00e9v\u00e9nements - Palace Natali","twitter:description":"Votre journ\u00e9e sp\u00e9ciale m\u00e9rite un lieu sp\u00e9cial. Que la beaut\u00e9 et la magie du Palace Natali rendent vos souvenirs encore plus merveilleux. Situ\u00e9 en plein c\u0153ur de la ville, mais suffisamment \u00e9loign\u00e9 de son agitation, le Palace Natali est, dans cette oasis de paix, le lieu parfait pour diff\u00e9rentes occasions : \u00e9v\u00e9nements priv\u00e9s et professionnels,"},"aioseo_meta_data":{"post_id":"2900","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2023-12-13 12:19:36","updated":"2025-09-12 12:15:29","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/palacenatali.com\/fr\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMariages et \u00e9v\u00e9nements\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/palacenatali.com\/fr\/"},{"label":"Mariages et \u00e9v\u00e9nements","link":"https:\/\/palacenatali.com\/fr\/mariages-et-evenements\/"}],"_links":{"self":[{"href":"https:\/\/palacenatali.com\/fr\/wp-json\/wp\/v2\/pages\/2900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/palacenatali.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/palacenatali.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/palacenatali.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/palacenatali.com\/fr\/wp-json\/wp\/v2\/comments?post=2900"}],"version-history":[{"count":22,"href":"https:\/\/palacenatali.com\/fr\/wp-json\/wp\/v2\/pages\/2900\/revisions"}],"predecessor-version":[{"id":7587,"href":"https:\/\/palacenatali.com\/fr\/wp-json\/wp\/v2\/pages\/2900\/revisions\/7587"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/palacenatali.com\/fr\/wp-json\/wp\/v2\/media\/6386"}],"wp:attachment":[{"href":"https:\/\/palacenatali.com\/fr\/wp-json\/wp\/v2\/media?parent=2900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}