{"id":2891,"date":"2022-12-30T14:41:12","date_gmt":"2022-12-30T13:41:12","guid":{"rendered":"https:\/\/new-web.palacenatali.com\/send-inquiry\/"},"modified":"2024-01-10T14:12:23","modified_gmt":"2024-01-10T13:12:23","slug":"envoyez-une-demande","status":"publish","type":"page","link":"https:\/\/palacenatali.com\/fr\/envoyez-une-demande\/","title":{"rendered":"Envoyez une demande"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":2539,"parent":0,"menu_order":59,"comment_status":"closed","ping_status":"closed","template":"template-inquiry.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2891","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/palacenatali.com\/fr\/envoyez-une-demande\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Palace Natali -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Envoyez une demande - Palace Natali\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/palacenatali.com\/fr\/envoyez-une-demande\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-12-30T13:41:12+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-01-10T13:12:23+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Envoyez une demande - Palace Natali\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/envoyez-une-demande\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/envoyez-une-demande\\\/#listItem\",\"name\":\"Envoyez une demande\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/envoyez-une-demande\\\/#listItem\",\"position\":2,\"name\":\"Envoyez une demande\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/#organization\",\"name\":\"Palace Natali\",\"url\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/\",\"telephone\":\"+38520325550\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/palacenatali.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo-natali.svg\",\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/envoyez-une-demande\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/envoyez-une-demande\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/envoyez-une-demande\\\/#webpage\",\"url\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/envoyez-une-demande\\\/\",\"name\":\"Envoyez une demande - Palace Natali\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/envoyez-une-demande\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/palacenatali.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Natali-184-final_1080-1.jpg\",\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/envoyez-une-demande\\\/#mainImage\",\"width\":1920,\"height\":1080},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/envoyez-une-demande\\\/#mainImage\"},\"datePublished\":\"2022-12-30T14:41:12+01:00\",\"dateModified\":\"2024-01-10T14:12:23+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/\",\"name\":\"Palace Natali\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/palacenatali.com\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Envoyez une demande - Palace Natali","description":"","canonical_url":"https:\/\/palacenatali.com\/fr\/envoyez-une-demande\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/palacenatali.com\/fr\/envoyez-une-demande\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/palacenatali.com\/fr\/#listItem","position":1,"name":"Home","item":"https:\/\/palacenatali.com\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/palacenatali.com\/fr\/envoyez-une-demande\/#listItem","name":"Envoyez une demande"}},{"@type":"ListItem","@id":"https:\/\/palacenatali.com\/fr\/envoyez-une-demande\/#listItem","position":2,"name":"Envoyez une demande","previousItem":{"@type":"ListItem","@id":"https:\/\/palacenatali.com\/fr\/#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/palacenatali.com\/fr\/#organization","name":"Palace Natali","url":"https:\/\/palacenatali.com\/fr\/","telephone":"+38520325550","logo":{"@type":"ImageObject","url":"https:\/\/palacenatali.com\/wp-content\/uploads\/2024\/10\/logo-natali.svg","@id":"https:\/\/palacenatali.com\/fr\/envoyez-une-demande\/#organizationLogo"},"image":{"@id":"https:\/\/palacenatali.com\/fr\/envoyez-une-demande\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/palacenatali.com\/fr\/envoyez-une-demande\/#webpage","url":"https:\/\/palacenatali.com\/fr\/envoyez-une-demande\/","name":"Envoyez une demande - Palace Natali","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/palacenatali.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/palacenatali.com\/fr\/envoyez-une-demande\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/palacenatali.com\/wp-content\/uploads\/2023\/10\/Natali-184-final_1080-1.jpg","@id":"https:\/\/palacenatali.com\/fr\/envoyez-une-demande\/#mainImage","width":1920,"height":1080},"primaryImageOfPage":{"@id":"https:\/\/palacenatali.com\/fr\/envoyez-une-demande\/#mainImage"},"datePublished":"2022-12-30T14:41:12+01:00","dateModified":"2024-01-10T14:12:23+01:00"},{"@type":"WebSite","@id":"https:\/\/palacenatali.com\/fr\/#website","url":"https:\/\/palacenatali.com\/fr\/","name":"Palace Natali","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/palacenatali.com\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Palace Natali -","og:type":"article","og:title":"Envoyez une demande - Palace Natali","og:url":"https:\/\/palacenatali.com\/fr\/envoyez-une-demande\/","article:published_time":"2022-12-30T13:41:12+00:00","article:modified_time":"2024-01-10T13:12:23+00:00","twitter:card":"summary_large_image","twitter:title":"Envoyez une demande - Palace Natali"},"aioseo_meta_data":{"post_id":"2891","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-12-13 12:20:09","updated":"2025-07-28 08:51:07","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/palacenatali.com\/fr\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEnvoyez une demande\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/palacenatali.com\/fr\/"},{"label":"Envoyez une demande","link":"https:\/\/palacenatali.com\/fr\/envoyez-une-demande\/"}],"_links":{"self":[{"href":"https:\/\/palacenatali.com\/fr\/wp-json\/wp\/v2\/pages\/2891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/palacenatali.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/palacenatali.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/palacenatali.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/palacenatali.com\/fr\/wp-json\/wp\/v2\/comments?post=2891"}],"version-history":[{"count":1,"href":"https:\/\/palacenatali.com\/fr\/wp-json\/wp\/v2\/pages\/2891\/revisions"}],"predecessor-version":[{"id":3603,"href":"https:\/\/palacenatali.com\/fr\/wp-json\/wp\/v2\/pages\/2891\/revisions\/3603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/palacenatali.com\/fr\/wp-json\/wp\/v2\/media\/2539"}],"wp:attachment":[{"href":"https:\/\/palacenatali.com\/fr\/wp-json\/wp\/v2\/media?parent=2891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}